{"id":814,"count":1,"description":"","link":"https:\/\/queensyes.com\/en\/tag\/the-original-project-was-developed-by-robert-e-lee-in-1857","name":"The original project was developed by Robert E. Lee in 1857","slug":"the-original-project-was-developed-by-robert-e-lee-in-1857","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/queensyes.com\/en\/wp-json\/wp\/v2\/tags\/814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queensyes.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/queensyes.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/queensyes.com\/en\/wp-json\/wp\/v2\/posts?tags=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}